{"id":342,"date":"2026-05-06T10:32:34","date_gmt":"2026-05-06T08:32:34","guid":{"rendered":"https:\/\/chur2028.ch\/sportart\/short-track\/"},"modified":"2026-05-19T17:06:48","modified_gmt":"2026-05-19T15:06:48","slug":"short-track","status":"publish","type":"sportart","link":"https:\/\/chur2028.compresso.website\/en\/sportart\/short-track\/","title":{"rendered":"Short Track"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","region":[],"class_list":["post-342","sportart","type-sportart","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/chur2028.compresso.website\/en\/wp-json\/wp\/v2\/sportart\/342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chur2028.compresso.website\/en\/wp-json\/wp\/v2\/sportart"}],"about":[{"href":"https:\/\/chur2028.compresso.website\/en\/wp-json\/wp\/v2\/types\/sportart"}],"wp:attachment":[{"href":"https:\/\/chur2028.compresso.website\/en\/wp-json\/wp\/v2\/media?parent=342"}],"wp:term":[{"taxonomy":"region","embeddable":true,"href":"https:\/\/chur2028.compresso.website\/en\/wp-json\/wp\/v2\/region?post=342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}